{"id":1955,"date":"2026-07-15T03:00:41","date_gmt":"2026-07-15T03:00:41","guid":{"rendered":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/kurse\/rehasport-13\/"},"modified":"2026-07-15T03:00:41","modified_gmt":"2026-07-15T03:00:41","slug":"rehasport-13","status":"publish","type":"kurse","link":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/kurse\/rehasport-13\/","title":{"rendered":"Rehasport"},"template":"","meta":{"uebungsleitung":"Anne","rehasportart":"Orthop\u00e4die","kurszeit_von":"16:30","kurszeit_bis":"17:15","max_gruppengroesse":"14","adresse":"Heinrich-Hertz-Stra\u00dfe 10 (Flugplatzgel\u00e4nde), 54634, Bitburg","outdoor":"Nein","outdoor_adresse":"","geschlechtsspezifische_gruppe":"Keine Beschr\u00e4nkung","alter_rehasportgruppe":"Keine Beschr\u00e4nkung","angebot_fuer_schwerstbehinderte":"Nein","raumbezeichnung":"Kursraum 1","strasse_und_hausnummer_raum":"Heinrich-Hertz-Stra\u00dfe 10","stadt_raum":"Bitburg","postleitzahl_raum":"54634","raumgroesse_m_raum":"74,92","ggf_wasserflaeche_m_raum":"","raumart":"Kursraum","barrierefrei":"Ja","umkleidemoeglichkeiten":"Ja","1_hilfe_ausstattung_ist_vorhanden":"Ja","defibrillator_vorhanden":"Nein","gruppen_id":"29126","wochentag":"Freitag"},"wochentage":[26],"class_list":["post-1955","kurse","type-kurse","status-publish","hentry","wochentage-freitag"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rehasport - Dianas Kurs- und Therapiezentrum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/kurse\/rehasport-13\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rehasport - Dianas Kurs- und Therapiezentrum\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/kurse\/rehasport-13\/\" \/>\n<meta property=\"og:site_name\" content=\"Dianas Kurs- und Therapiezentrum\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/kurse\/rehasport-13\/\",\"url\":\"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/kurse\/rehasport-13\/\",\"name\":\"Rehasport - Dianas Kurs- und Therapiezentrum\",\"isPartOf\":{\"@id\":\"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/#website\"},\"datePublished\":\"2026-07-15T03:00:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/kurse\/rehasport-13\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/kurse\/rehasport-13\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/kurse\/rehasport-13\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kurse\",\"item\":\"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/kurse\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rehasport\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/#website\",\"url\":\"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/\",\"name\":\"Dianas Kurs- und Therapiezentrum\",\"description\":\"Rehasport in Bitburg\",\"publisher\":{\"@id\":\"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/#organization\",\"name\":\"Dianas Kurs- und Therapiezentrum\",\"url\":\"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/rehasportportal.de\/wp-content\/uploads\/sites\/604\/sites\/604\/2025\/07\/Rehasport_Portal_Logo_rgb.png\",\"contentUrl\":\"https:\/\/rehasportportal.de\/wp-content\/uploads\/sites\/604\/sites\/604\/2025\/07\/Rehasport_Portal_Logo_rgb.png\",\"width\":945,\"height\":295,\"caption\":\"Dianas Kurs- und Therapiezentrum\"},\"image\":{\"@id\":\"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rehasport - Dianas Kurs- und Therapiezentrum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/kurse\/rehasport-13\/","og_locale":"de_DE","og_type":"article","og_title":"Rehasport - Dianas Kurs- und Therapiezentrum","og_url":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/kurse\/rehasport-13\/","og_site_name":"Dianas Kurs- und Therapiezentrum","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/kurse\/rehasport-13\/","url":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/kurse\/rehasport-13\/","name":"Rehasport - Dianas Kurs- und Therapiezentrum","isPartOf":{"@id":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/#website"},"datePublished":"2026-07-15T03:00:41+00:00","breadcrumb":{"@id":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/kurse\/rehasport-13\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/kurse\/rehasport-13\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/kurse\/rehasport-13\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/"},{"@type":"ListItem","position":2,"name":"Kurse","item":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/kurse\/"},{"@type":"ListItem","position":3,"name":"Rehasport"}]},{"@type":"WebSite","@id":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/#website","url":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/","name":"Dianas Kurs- und Therapiezentrum","description":"Rehasport in Bitburg","publisher":{"@id":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/#organization","name":"Dianas Kurs- und Therapiezentrum","url":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/#\/schema\/logo\/image\/","url":"https:\/\/rehasportportal.de\/wp-content\/uploads\/sites\/604\/sites\/604\/2025\/07\/Rehasport_Portal_Logo_rgb.png","contentUrl":"https:\/\/rehasportportal.de\/wp-content\/uploads\/sites\/604\/sites\/604\/2025\/07\/Rehasport_Portal_Logo_rgb.png","width":945,"height":295,"caption":"Dianas Kurs- und Therapiezentrum"},"image":{"@id":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/wp-json\/wp\/v2\/kurse\/1955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/wp-json\/wp\/v2\/kurse"}],"about":[{"href":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/wp-json\/wp\/v2\/types\/kurse"}],"wp:attachment":[{"href":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/wp-json\/wp\/v2\/media?parent=1955"}],"wp:term":[{"taxonomy":"wochentage","embeddable":true,"href":"https:\/\/rehasportportal.de\/dianas-kurs-und-therapiezentrum\/wp-json\/wp\/v2\/wochentage?post=1955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}