{"id":1879,"date":"2026-03-27T04:55:16","date_gmt":"2026-03-27T04:55:16","guid":{"rendered":"https:\/\/rehasportportal.de\/vitalis-benrath-rvp\/kurse\/rehasport-24\/"},"modified":"2026-05-07T03:00:43","modified_gmt":"2026-05-07T03:00:43","slug":"rehasport-24","status":"publish","type":"kurse","link":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/kurse\/rehasport-24\/","title":{"rendered":"Rehasport"},"template":"","meta":{"uebungsleitung":"Holger","rehasportart":"Orthop\u00e4die","kurszeit_von":"11:00","kurszeit_bis":"11:45","max_gruppengroesse":"15","adresse":"Professor-Oehler-Stra\u00dfe 7, 40589, Nettetal","outdoor":"Nein","outdoor_adresse":"","geschlechtsspezifische_gruppe":"Keine Beschr\u00e4nkung","alter_rehasportgruppe":"Keine Beschr\u00e4nkung","angebot_fuer_schwerstbehinderte":"Nein","raumbezeichnung":"Gymnastikraum 1","strasse_und_hausnummer_raum":"Professor-Oehler-Stra\u00dfe 7","stadt_raum":"Nettetal","postleitzahl_raum":"40589","raumgroesse_m_raum":"107","ggf_wasserflaeche_m_raum":"","raumart":"Kursraum","barrierefrei":"Nein","umkleidemoeglichkeiten":"Ja","1_hilfe_ausstattung_ist_vorhanden":"Ja","defibrillator_vorhanden":"Nein","gruppen_id":"23443","wochentag":"Mittwoch"},"wochentage":[24],"class_list":["post-1879","kurse","type-kurse","status-publish","hentry","wochentage-mittwoch"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rehasport - In time fitness GbR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/kurse\/rehasport-24\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rehasport - In time fitness GbR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/kurse\/rehasport-24\/\" \/>\n<meta property=\"og:site_name\" content=\"In time fitness GbR\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T03:00:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/kurse\/rehasport-24\/\",\"url\":\"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/kurse\/rehasport-24\/\",\"name\":\"Rehasport - In time fitness GbR\",\"isPartOf\":{\"@id\":\"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/#website\"},\"datePublished\":\"2026-03-27T04:55:16+00:00\",\"dateModified\":\"2026-05-07T03:00:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/kurse\/rehasport-24\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/kurse\/rehasport-24\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/kurse\/rehasport-24\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kurse\",\"item\":\"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/kurse\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rehasport\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/#website\",\"url\":\"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/\",\"name\":\"In time fitness GbR\",\"description\":\"Rehasport in Nettetal\",\"publisher\":{\"@id\":\"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/#organization\",\"name\":\"In time fitness GbR\",\"url\":\"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/rehasportportal.de\/wp-content\/uploads\/sites\/593\/sites\/593\/2025\/07\/Rehasport_Portal_Logo_rgb.png\",\"contentUrl\":\"https:\/\/rehasportportal.de\/wp-content\/uploads\/sites\/593\/sites\/593\/2025\/07\/Rehasport_Portal_Logo_rgb.png\",\"width\":945,\"height\":295,\"caption\":\"In time fitness GbR\"},\"image\":{\"@id\":\"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rehasport - In time fitness GbR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/kurse\/rehasport-24\/","og_locale":"de_DE","og_type":"article","og_title":"Rehasport - In time fitness GbR","og_url":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/kurse\/rehasport-24\/","og_site_name":"In time fitness GbR","article_modified_time":"2026-05-07T03:00:43+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/kurse\/rehasport-24\/","url":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/kurse\/rehasport-24\/","name":"Rehasport - In time fitness GbR","isPartOf":{"@id":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/#website"},"datePublished":"2026-03-27T04:55:16+00:00","dateModified":"2026-05-07T03:00:43+00:00","breadcrumb":{"@id":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/kurse\/rehasport-24\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rehasportportal.de\/in-time-fitness-gbr\/kurse\/rehasport-24\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/kurse\/rehasport-24\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/"},{"@type":"ListItem","position":2,"name":"Kurse","item":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/kurse\/"},{"@type":"ListItem","position":3,"name":"Rehasport"}]},{"@type":"WebSite","@id":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/#website","url":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/","name":"In time fitness GbR","description":"Rehasport in Nettetal","publisher":{"@id":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/#organization","name":"In time fitness GbR","url":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/#\/schema\/logo\/image\/","url":"https:\/\/rehasportportal.de\/wp-content\/uploads\/sites\/593\/sites\/593\/2025\/07\/Rehasport_Portal_Logo_rgb.png","contentUrl":"https:\/\/rehasportportal.de\/wp-content\/uploads\/sites\/593\/sites\/593\/2025\/07\/Rehasport_Portal_Logo_rgb.png","width":945,"height":295,"caption":"In time fitness GbR"},"image":{"@id":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/wp-json\/wp\/v2\/kurse\/1879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/wp-json\/wp\/v2\/kurse"}],"about":[{"href":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/wp-json\/wp\/v2\/types\/kurse"}],"wp:attachment":[{"href":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/wp-json\/wp\/v2\/media?parent=1879"}],"wp:term":[{"taxonomy":"wochentage","embeddable":true,"href":"https:\/\/rehasportportal.de\/in-time-fitness-gbr\/wp-json\/wp\/v2\/wochentage?post=1879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}