{"id":450,"date":"2025-08-08T11:42:11","date_gmt":"2025-08-08T11:42:11","guid":{"rendered":"https:\/\/rehasportportal.de\/?page_id=450"},"modified":"2026-06-06T19:08:48","modified_gmt":"2026-06-06T19:08:48","slug":"datenschutz","status":"publish","type":"page","link":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/datenschutz\/","title":{"rendered":"Datenschutz"},"content":{"rendered":"<h1>1. Datenschutz auf einen Blick<\/h1>\n<h3>Allgemeine Hinweise<\/h3>\n<p>Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung.<\/p>\n<h3>Datenerfassung auf dieser Website<\/h3>\n<h4>Wer ist verantwortlich f\u00fcr die Datenerfassung auf dieser Website?<\/h4>\n<p>Die Datenverarbeitung auf dieser Website erfolgt durch den Websitebetreiber. Dessen Kontaktdaten k\u00f6nnen Sie dem Abschnitt \u201eHinweis zur Verantwortlichen Stelle\u201c in dieser Datenschutzerkl\u00e4rung entnehmen.<\/p>\n<h4>Wie erfassen wir Ihre Daten?<\/h4>\n<p>Ihre Daten werden zum einen dadurch erhoben, dass Sie uns diese mitteilen. Hierbei kann es sich z.&nbsp;B. um Daten handeln, die Sie in ein Kontaktformular eingeben.<\/p>\n<p>Andere Daten werden automatisch oder nach Ihrer Einwilligung beim Besuch der Website durch unsere IT-Systeme erfasst. Das sind vor allem technische Daten (z.&nbsp;B. Internetbrowser, Betriebssystem oder Uhrzeit des Seitenaufrufs). Die Erfassung dieser Daten erfolgt automatisch, sobald Sie diese Website betreten.<\/p>\n<h4>Wof\u00fcr nutzen wir Ihre Daten?<\/h4>\n<p>Ein Teil der Daten wird erhoben, um eine fehlerfreie Bereitstellung der Website zu gew\u00e4hrleisten. Andere Daten k\u00f6nnen zur Analyse Ihres Nutzerverhaltens verwendet werden. Sofern \u00fcber die Website Vertr\u00e4ge geschlossen oder angebahnt werden k\u00f6nnen, werden die \u00fcbermittelten Daten auch f\u00fcr Vertragsangebote, Bestellungen oder sonstige Auftragsanfragen verarbeitet.<\/p>\n<h4>Welche Rechte haben Sie bez\u00fcglich Ihrer Daten?<\/h4>\n<p>Sie haben jederzeit das Recht, unentgeltlich Auskunft \u00fcber Herkunft, Empf\u00e4nger und Zweck Ihrer gespeicherten personenbezogenen Daten zu erhalten. Sie haben au\u00dferdem ein Recht, die Berichtigung oder L\u00f6schung dieser Daten zu verlangen. Wenn Sie eine Einwilligung zur Datenverarbeitung erteilt haben, k\u00f6nnen Sie diese Einwilligung jederzeit f\u00fcr die Zukunft widerrufen. Au\u00dferdem haben Sie das Recht, unter bestimmten Umst\u00e4nden die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Des Weiteren steht Ihnen ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu.<\/p>\n<p>Hierzu sowie zu weiteren Fragen zum Thema Datenschutz k\u00f6nnen Sie sich jederzeit an uns wenden.<\/p>\n<h3>Analyse-Tools und Tools von Dritt\u00adanbietern<\/h3>\n<p>Beim Besuch dieser Website kann Ihr Surf-Verhalten statistisch ausgewertet werden. Das geschieht vor allem mit sogenannten Analyseprogrammen.<\/p>\n<p>Detaillierte Informationen zu diesen Analyseprogrammen finden Sie in der folgenden Datenschutzerkl\u00e4rung.<\/p>\n<h2>2. Hosting<\/h2>\n<p>Wir hosten die Inhalte unserer Website bei folgendem Anbieter:<\/p>\n<h3>Externes Hosting<\/h3>\n<p>Diese Website wird extern gehostet. Die personenbezogenen Daten, die auf dieser Website erfasst werden, werden auf den Servern des Hosters \/ der Hoster gespeichert. Hierbei kann es sich v.&nbsp;a. um IP-Adressen, Kontaktanfragen, Meta- und Kommunikationsdaten, Vertragsdaten, Kontaktdaten, Namen, Websitezugriffe und sonstige Daten, die \u00fcber eine Website generiert werden, handeln.<\/p>\n<p>Das externe Hosting erfolgt zum Zwecke der Vertragserf\u00fcllung gegen\u00fcber unseren potenziellen und bestehenden Kunden (Art. 6 Abs. 1 lit. b DSGVO) und im Interesse einer sicheren, schnellen und effizienten Bereitstellung unseres Online-Angebots durch einen professionellen Anbieter (Art. 6 Abs. 1 lit. f DSGVO). Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger\u00e4t des Nutzers (z.&nbsp;B. Device-Fingerprinting) im Sinne des TDDDG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Unser(e) Hoster wird bzw. werden Ihre Daten nur insoweit verarbeiten, wie dies zur Erf\u00fcllung seiner Leistungspflichten erforderlich ist und unsere Weisungen in Bezug auf diese Daten befolgen.<\/p>\n<p>Wir setzen folgende(n) Hoster ein:<\/p>\n<p>Hostinger<\/p>\n<h2>3. Allgemeine Hinweise und Pflicht\u00adinformationen<\/h2>\n<h3>Datenschutz<\/h3>\n<p>Die Betreiber dieser Seiten nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Wir behandeln Ihre personenbezogenen Daten vertraulich und entsprechend den gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung.<\/p>\n<p>Wenn Sie diese Website benutzen, werden verschiedene personenbezogene Daten erhoben. Personenbezogene Daten sind Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Die vorliegende Datenschutzerkl\u00e4rung erl\u00e4utert, welche Daten wir erheben und wof\u00fcr wir sie nutzen. Sie erl\u00e4utert auch, wie und zu welchem Zweck das geschieht.<\/p>\n<p>Wir weisen darauf hin, dass die Daten\u00fcbertragung im Internet (z.&nbsp;B. bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich.<\/p>\n<h3>Hinweis zur verantwortlichen Stelle<\/h3>\n<p>Die verantwortliche Stelle f\u00fcr die Datenverarbeitung auf dieser Website ist:<\/p>\n<p>RehaVitalisPlus e.V.<\/p>\n<p>Prof. Oehler Stra\u00dfe 7<\/p>\n<p>40589 D\u00fcsseldorf<\/p>\n<p>Telefon: +49-211-99540438<br \/>E-Mail: info@rehavitalisplus.de<\/p>\n<p>Verantwortliche Stelle ist die nat\u00fcrliche oder juristische Person, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten (z.&nbsp;B. Namen, E-Mail-Adressen o. \u00c4.) entscheidet.<\/p>\n<h3>Speicherdauer<\/h3>\n<p>Soweit innerhalb dieser Datenschutzerkl\u00e4rung keine speziellere Speicherdauer genannt wurde, verbleiben Ihre personenbezogenen Daten bei uns, bis der Zweck f\u00fcr die Datenverarbeitung entf\u00e4llt. Wenn Sie ein berechtigtes L\u00f6schersuchen geltend machen oder eine Einwilligung zur Datenverarbeitung widerrufen, werden Ihre Daten gel\u00f6scht, sofern wir keine anderen rechtlich zul\u00e4ssigen Gr\u00fcnde f\u00fcr die Speicherung Ihrer personenbezogenen Daten haben (z.&nbsp;B. steuer- oder handelsrechtliche Aufbewahrungsfristen); im letztgenannten Fall erfolgt die L\u00f6schung nach Fortfall dieser Gr\u00fcnde.<\/p>\n<h3>Allgemeine Hinweise zu den Rechtsgrundlagen der Datenverarbeitung auf dieser Website<\/h3>\n<p>Sofern Sie in die Datenverarbeitung eingewilligt haben, verarbeiten wir Ihre personenbezogenen Daten auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO bzw. Art. 9 Abs. 2 lit. a DSGVO, sofern besondere Datenkategorien nach Art. 9 Abs. 1 DSGVO verarbeitet werden. Im Falle einer ausdr\u00fccklichen Einwilligung in die \u00dcbertragung personenbezogener Daten in Drittstaaten erfolgt die Datenverarbeitung au\u00dferdem auf Grundlage von Art. 49 Abs. 1 lit. a DSGVO. Sofern Sie in die Speicherung von Cookies oder in den Zugriff auf Informationen in Ihr Endger\u00e4t (z.&nbsp;B. via Device-Fingerprinting) eingewilligt haben, erfolgt die Datenverarbeitung zus\u00e4tzlich auf Grundlage von \u00a7 25 Abs. 1 TDDDG. Die Einwilligung ist jederzeit widerrufbar. Sind Ihre Daten zur Vertragserf\u00fcllung oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich, verarbeiten wir Ihre Daten auf Grundlage des Art. 6 Abs. 1 lit. b DSGVO. Des Weiteren verarbeiten wir Ihre Daten, sofern diese zur Erf\u00fcllung einer rechtlichen Verpflichtung erforderlich sind auf Grundlage von Art. 6 Abs. 1 lit. c DSGVO. Die Datenverarbeitung kann ferner auf Grundlage unseres berechtigten Interesses nach Art. 6 Abs. 1 lit. f DSGVO erfolgen. \u00dcber die jeweils im Einzelfall einschl\u00e4gigen Rechtsgrundlagen wird in den folgenden Abs\u00e4tzen dieser Datenschutzerkl\u00e4rung informiert.<\/p>\n<h3>Hinweis zur Datenweitergabe in datenschutzrechtlich nicht sichere Drittstaaten sowie die Weitergabe an US-Unternehmen, die nicht DPF-zertifiziert sind<\/h3>\n<p>Wir verwenden unter anderem Tools von Unternehmen mit Sitz in datenschutzrechtlich nicht sicheren Drittstaaten sowie US-Tools, deren Anbieter nicht nach dem EU-US-Data Privacy Framework (DPF) zertifiziert sind. Wenn diese Tools aktiv sind, k\u00f6nnen Ihre personenbezogene Daten in diese Staaten \u00fcbertragen und dort verarbeitet werden. Wir weisen darauf hin, dass in datenschutzrechtlich unsicheren Drittstaaten kein mit der EU vergleichbares Datenschutzniveau garantiert werden kann.<\/p>\n<p>Wir weisen darauf hin, dass die USA als sicherer Drittstaat grunds\u00e4tzlich ein mit der EU vergleichbares Datenschutzniveau aufweisen. Eine Daten\u00fcbertragung in die USA ist danach zul\u00e4ssig, wenn der Empf\u00e4nger eine Zertifizierung unter dem \u201eEU-US Data Privacy Framework\u201c (DPF) besitzt oder \u00fcber geeignete zus\u00e4tzliche Garantien verf\u00fcgt. Informationen zu \u00dcbermittlungen an Drittstaaten einschlie\u00dflich der Datenempf\u00e4nger finden Sie in dieser Datenschutzerkl\u00e4rung.<\/p>\n<h3>Empf\u00e4nger von personenbezogenen Daten<\/h3>\n<p>Im Rahmen unserer Gesch\u00e4ftst\u00e4tigkeit arbeiten wir mit verschiedenen externen Stellen zusammen. Dabei ist teilweise auch eine \u00dcbermittlung von personenbezogenen Daten an diese externen Stellen erforderlich. Wir geben personenbezogene Daten nur dann an externe Stellen weiter, wenn dies im Rahmen einer Vertragserf\u00fcllung erforderlich ist, wenn wir gesetzlich hierzu verpflichtet sind (z.&nbsp;B. Weitergabe von Daten an Steuerbeh\u00f6rden), wenn wir ein berechtigtes Interesse nach Art. 6 Abs. 1 lit. f DSGVO an der Weitergabe haben oder wenn eine sonstige Rechtsgrundlage die Datenweitergabe erlaubt. Beim Einsatz von Auftragsverarbeitern geben wir personenbezogene Daten unserer Kunden nur auf Grundlage eines g\u00fcltigen Vertrags \u00fcber Auftragsverarbeitung weiter. Im Falle einer gemeinsamen Verarbeitung wird ein Vertrag \u00fcber gemeinsame Verarbeitung geschlossen.<\/p>\n<h3>Widerruf Ihrer Einwilligung zur Datenverarbeitung<\/h3>\n<p>Viele Datenverarbeitungsvorg\u00e4nge sind nur mit Ihrer ausdr\u00fccklichen Einwilligung m\u00f6glich. Sie k\u00f6nnen eine bereits erteilte Einwilligung jederzeit widerrufen. Die Rechtm\u00e4\u00dfigkeit der bis zum Widerruf erfolgten Datenverarbeitung bleibt vom Widerruf unber\u00fchrt.<\/p>\n<h3>Widerspruchsrecht gegen die Datenerhebung in besonderen F\u00e4llen sowie gegen Direktwerbung (Art. 21 DSGVO)<\/h3>\n<p>WENN DIE DATENVERARBEITUNG AUF GRUNDLAGE VON ART. 6 ABS. 1 LIT. E ODER F DSGVO ERFOLGT, HABEN SIE JEDERZEIT DAS RECHT, AUS GR\u00dcNDEN, DIE SICH AUS IHRER BESONDEREN SITUATION ERGEBEN, GEGEN DIE VERARBEITUNG IHRER PERSONENBEZOGENEN DATEN WIDERSPRUCH EINZULEGEN; DIES GILT AUCH F\u00dcR EIN AUF DIESE BESTIMMUNGEN GEST\u00dcTZTES PROFILING. DIE JEWEILIGE RECHTSGRUNDLAGE, AUF DENEN EINE VERARBEITUNG BERUHT, ENTNEHMEN SIE DIESER DATENSCHUTZERKL\u00c4RUNG. WENN SIE WIDERSPRUCH EINLEGEN, WERDEN WIR IHRE BETROFFENEN PERSONENBEZOGENEN DATEN NICHT MEHR VERARBEITEN, ES SEI DENN, WIR K\u00d6NNEN ZWINGENDE SCHUTZW\u00dcRDIGE GR\u00dcNDE F\u00dcR DIE VERARBEITUNG NACHWEISEN, DIE IHRE INTERESSEN, RECHTE UND FREIHEITEN \u00dcBERWIEGEN ODER DIE VERARBEITUNG DIENT DER GELTENDMACHUNG, AUS\u00dcBUNG ODER VERTEIDIGUNG VON RECHTSANSPR\u00dcCHEN (WIDERSPRUCH NACH ART. 21 ABS. 1 DSGVO).<\/p>\n<p>WERDEN IHRE PERSONENBEZOGENEN DATEN VERARBEITET, UM DIREKTWERBUNG ZU BETREIBEN, SO HABEN SIE DAS RECHT, JEDERZEIT WIDERSPRUCH GEGEN DIE VERARBEITUNG SIE BETREFFENDER PERSONENBEZOGENER DATEN ZUM ZWECKE DERARTIGER WERBUNG EINZULEGEN; DIES GILT AUCH F\u00dcR DAS PROFILING, SOWEIT ES MIT SOLCHER DIREKTWERBUNG IN VERBINDUNG STEHT. WENN SIE WIDERSPRECHEN, WERDEN IHRE PERSONENBEZOGENEN DATEN ANSCHLIESSEND NICHT MEHR ZUM ZWECKE DER DIREKTWERBUNG VERWENDET (WIDERSPRUCH NACH ART. 21 ABS. 2 DSGVO).<\/p>\n<h3>Beschwerde\u00adrecht bei der zust\u00e4ndigen Aufsichts\u00adbeh\u00f6rde<\/h3>\n<p>Im Falle von Verst\u00f6\u00dfen gegen die DSGVO steht den Betroffenen ein Beschwerderecht bei einer Aufsichtsbeh\u00f6rde, insbesondere in dem Mitgliedstaat ihres gew\u00f6hnlichen Aufenthalts, ihres Arbeitsplatzes oder des Orts des mutma\u00dflichen Versto\u00dfes zu. Das Beschwerderecht besteht unbeschadet anderweitiger verwaltungsrechtlicher oder gerichtlicher Rechtsbehelfe.<\/p>\n<h3>Recht auf Daten\u00ad\u00fcbertrag\u00adbarkeit<\/h3>\n<p>Sie haben das Recht, Daten, die wir auf Grundlage Ihrer Einwilligung oder in Erf\u00fcllung eines Vertrags automatisiert verarbeiten, an sich oder an einen Dritten in einem g\u00e4ngigen, maschinenlesbaren Format aush\u00e4ndigen zu lassen. Sofern Sie die direkte \u00dcbertragung der Daten an einen anderen Verantwortlichen verlangen, erfolgt dies nur, soweit es technisch machbar ist.<\/p>\n<h3>Auskunft, Berichtigung und L\u00f6schung<\/h3>\n<p>Sie haben im Rahmen der geltenden gesetzlichen Bestimmungen jederzeit das Recht auf unentgeltliche Auskunft \u00fcber Ihre gespeicherten personenbezogenen Daten, deren Herkunft und Empf\u00e4nger und den Zweck der Datenverarbeitung und ggf. ein Recht auf Berichtigung oder L\u00f6schung dieser Daten. Hierzu sowie zu weiteren Fragen zum Thema personenbezogene Daten k\u00f6nnen Sie sich jederzeit an uns wenden.<\/p>\n<h3>Recht auf Einschr\u00e4nkung der Verarbeitung<\/h3>\n<p>Sie haben das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Hierzu k\u00f6nnen Sie sich jederzeit an uns wenden. Das Recht auf Einschr\u00e4nkung der Verarbeitung besteht in folgenden F\u00e4llen:<\/p>\n<ul>\n<li>Wenn Sie die Richtigkeit Ihrer bei uns gespeicherten personenbezogenen Daten bestreiten, ben\u00f6tigen wir in der Regel Zeit, um dies zu \u00fcberpr\u00fcfen. F\u00fcr die Dauer der Pr\u00fcfung haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n<li>Wenn die Verarbeitung Ihrer personenbezogenen Daten unrechtm\u00e4\u00dfig geschah\/geschieht, k\u00f6nnen Sie statt der L\u00f6schung die Einschr\u00e4nkung der Datenverarbeitung verlangen.<\/li>\n<li>Wenn wir Ihre personenbezogenen Daten nicht mehr ben\u00f6tigen, Sie sie jedoch zur Aus\u00fcbung, Verteidigung oder Geltendmachung von Rechtsanspr\u00fcchen ben\u00f6tigen, haben Sie das Recht, statt der L\u00f6schung die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n<li>Wenn Sie einen Widerspruch nach Art. 21 Abs. 1 DSGVO eingelegt haben, muss eine Abw\u00e4gung zwischen Ihren und unseren Interessen vorgenommen werden. Solange noch nicht feststeht, wessen Interessen \u00fcberwiegen, haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n<\/ul>\n<p>Wenn Sie die Verarbeitung Ihrer personenbezogenen Daten eingeschr\u00e4nkt haben, d\u00fcrfen diese Daten \u2013 von ihrer Speicherung abgesehen \u2013 nur mit Ihrer Einwilligung oder zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen oder zum Schutz der Rechte einer anderen nat\u00fcrlichen oder juristischen Person oder aus Gr\u00fcnden eines wichtigen \u00f6ffentlichen Interesses der Europ\u00e4ischen Union oder eines Mitgliedstaats verarbeitet werden.<\/p>\n<h3>SSL- bzw. TLS-Verschl\u00fcsselung<\/h3>\n<p>Diese Seite nutzt aus Sicherheitsgr\u00fcnden und zum Schutz der \u00dcbertragung vertraulicher Inhalte, wie zum Beispiel Bestellungen oder Anfragen, die Sie an uns als Seitenbetreiber senden, eine SSL- bzw. TLS-Verschl\u00fcsselung. Eine verschl\u00fcsselte Verbindung erkennen Sie daran, dass die Adresszeile des Browsers von \u201ehttp:\/\/\u201c auf \u201ehttps:\/\/\u201c wechselt und an dem Schloss-Symbol in Ihrer Browserzeile.<\/p>\n<p>Wenn die SSL- bzw. TLS-Verschl\u00fcsselung aktiviert ist, k\u00f6nnen die Daten, die Sie an uns \u00fcbermitteln, nicht von Dritten mitgelesen werden.<\/p>\n<h2>4. Datenerfassung auf dieser Website<\/h2>\n<h3>Cookies<\/h3>\n<p>Unsere Internetseiten verwenden so genannte \u201eCookies\u201c. Cookies sind kleine Datenpakete und richten auf Ihrem Endger\u00e4t keinen Schaden an. Sie werden entweder vor\u00fcbergehend f\u00fcr die Dauer einer Sitzung (Session-Cookies) oder dauerhaft (permanente Cookies) auf Ihrem Endger\u00e4t gespeichert. Session-Cookies werden nach Ende Ihres Besuchs automatisch gel\u00f6scht. Permanente Cookies bleiben auf Ihrem Endger\u00e4t gespeichert, bis Sie diese selbst l\u00f6schen oder eine automatische L\u00f6schung durch Ihren Webbrowser erfolgt.<\/p>\n<p>Cookies k\u00f6nnen von uns (First-Party-Cookies) oder von Drittunternehmen stammen (sog. Third-Party-Cookies). Third-Party-Cookies erm\u00f6glichen die Einbindung bestimmter Dienstleistungen von Drittunternehmen innerhalb von Webseiten (z.&nbsp;B. Cookies zur Abwicklung von Zahlungsdienstleistungen).<\/p>\n<p>Cookies haben verschiedene Funktionen. Zahlreiche Cookies sind technisch notwendig, da bestimmte Webseitenfunktionen ohne diese nicht funktionieren w\u00fcrden (z.&nbsp;B. die Warenkorbfunktion oder die Anzeige von Videos). Andere Cookies k\u00f6nnen zur Auswertung des Nutzerverhaltens oder zu Werbezwecken verwendet werden.<\/p>\n<p>Cookies, die zur Durchf\u00fchrung des elektronischen Kommunikationsvorgangs, zur Bereitstellung bestimmter, von Ihnen erw\u00fcnschter Funktionen (z.&nbsp;B. f\u00fcr die Warenkorbfunktion) oder zur Optimierung der Website (z.&nbsp;B. Cookies zur Messung des Webpublikums) erforderlich sind (notwendige Cookies), werden auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO gespeichert, sofern keine andere Rechtsgrundlage angegeben wird. Der Websitebetreiber hat ein berechtigtes Interesse an der Speicherung von notwendigen Cookies zur technisch fehlerfreien und optimierten Bereitstellung seiner Dienste. Sofern eine Einwilligung zur Speicherung von Cookies und vergleichbaren Wiedererkennungstechnologien abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage dieser Einwilligung (Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG); die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Sie k\u00f6nnen Ihren Browser so einstellen, dass Sie \u00fcber das Setzen von Cookies informiert werden und Cookies nur im Einzelfall erlauben, die Annahme von Cookies f\u00fcr bestimmte F\u00e4lle oder generell ausschlie\u00dfen sowie das automatische L\u00f6schen der Cookies beim Schlie\u00dfen des Browsers aktivieren. Bei der Deaktivierung von Cookies kann die Funktionalit\u00e4t dieser Website eingeschr\u00e4nkt sein.<\/p>\n<p>Welche Cookies und Dienste auf dieser Website eingesetzt werden, k\u00f6nnen Sie dieser Datenschutzerkl\u00e4rung entnehmen.<\/p>\n<h3>Kontaktformular<\/h3>\n<p>Wenn Sie uns per Kontaktformular Anfragen zukommen lassen, werden Ihre Angaben aus dem Anfrageformular inklusive der von Ihnen dort angegebenen Kontaktdaten zwecks Bearbeitung der Anfrage und f\u00fcr den Fall von Anschlussfragen bei uns gespeichert. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.<\/p>\n<p>Die Verarbeitung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO, sofern Ihre Anfrage mit der Erf\u00fcllung eines Vertrags zusammenh\u00e4ngt oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich ist. In allen \u00fcbrigen F\u00e4llen beruht die Verarbeitung auf unserem berechtigten Interesse an der effektiven Bearbeitung der an uns gerichteten Anfragen (Art. 6 Abs. 1 lit. f DSGVO) oder auf Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO) sofern diese abgefragt wurde; die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Die von Ihnen im Kontaktformular eingegebenen Daten verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z.&nbsp;B. nach abgeschlossener Bearbeitung Ihrer Anfrage). Zwingende gesetzliche Bestimmungen \u2013 insbesondere Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p>\n<h3>Anfrage per E-Mail, Telefon oder Telefax<\/h3>\n<p>Wenn Sie uns per E-Mail, Telefon oder Telefax kontaktieren, wird Ihre Anfrage inklusive aller daraus hervorgehenden personenbezogenen Daten (Name, Anfrage) zum Zwecke der Bearbeitung Ihres Anliegens bei uns gespeichert und verarbeitet. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.<\/p>\n<p>Die Verarbeitung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO, sofern Ihre Anfrage mit der Erf\u00fcllung eines Vertrags zusammenh\u00e4ngt oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich ist. In allen \u00fcbrigen F\u00e4llen beruht die Verarbeitung auf unserem berechtigten Interesse an der effektiven Bearbeitung der an uns gerichteten Anfragen (Art. 6 Abs. 1 lit. f DSGVO) oder auf Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO) sofern diese abgefragt wurde; die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Die von Ihnen an uns per Kontaktanfragen \u00fcbersandten Daten verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z.&nbsp;B. nach abgeschlossener Bearbeitung Ihres Anliegens). Zwingende gesetzliche Bestimmungen \u2013 insbesondere gesetzliche Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p>\n<h2>5. Newsletter<\/h2>\n<h3>Newsletter\u00addaten<\/h3>\n<p>Wenn Sie den auf der Website angebotenen Newsletter beziehen m\u00f6chten, ben\u00f6tigen wir von Ihnen eine E-Mail-Adresse sowie Informationen, welche uns die \u00dcberpr\u00fcfung gestatten, dass Sie der Inhaber der angegebenen E-Mail-Adresse sind und mit dem Empfang des Newsletters einverstanden sind. Weitere Daten werden nicht bzw. nur auf freiwilliger Basis erhoben. Diese Daten verwenden wir ausschlie\u00dflich f\u00fcr den Versand der angeforderten Informationen und geben diese nicht an Dritte weiter.<\/p>\n<p>Die Verarbeitung der in das Newsletteranmeldeformular eingegebenen Daten erfolgt ausschlie\u00dflich auf Grundlage Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO). Die erteilte Einwilligung zur Speicherung der Daten, der E-Mail-Adresse sowie deren Nutzung zum Versand des Newsletters k\u00f6nnen Sie jederzeit widerrufen, etwa \u00fcber den \u201eAustragen\u201c-Link im Newsletter. Die Rechtm\u00e4\u00dfigkeit der bereits erfolgten Datenverarbeitungsvorg\u00e4nge bleibt vom Widerruf unber\u00fchrt.<\/p>\n<p>Die von Ihnen zum Zwecke des Newsletter-Bezugs bei uns hinterlegten Daten werden von uns bis zu Ihrer Austragung aus dem Newsletter bei uns bzw. dem Newsletterdiensteanbieter gespeichert und nach der Abbestellung des Newsletters oder nach Zweckfortfall aus der Newsletterverteilerliste gel\u00f6scht. Wir behalten uns vor, E-Mail-Adressen aus unserem Newsletterverteiler nach eigenem Ermessen im Rahmen unseres berechtigten Interesses nach Art. 6 Abs. 1 lit. f DSGVO zu l\u00f6schen oder zu sperren.<\/p>\n<p>Daten, die zu anderen Zwecken bei uns gespeichert wurden, bleiben hiervon unber\u00fchrt.<\/p>\n<p>Nach Ihrer Austragung aus der Newsletterverteilerliste wird Ihre E-Mail-Adresse bei uns bzw. dem Newsletterdiensteanbieter ggf. in einer Blacklist gespeichert, sofern dies zur Verhinderung k\u00fcnftiger Mailings erforderlich ist. Die Daten aus der Blacklist werden nur f\u00fcr diesen Zweck verwendet und nicht mit anderen Daten zusammengef\u00fchrt. Dies dient sowohl Ihrem Interesse als auch unserem Interesse an der Einhaltung der gesetzlichen Vorgaben beim Versand von Newslettern (berechtigtes Interesse im Sinne des Art. 6 Abs. 1 lit. f DSGVO). Die Speicherung in der Blacklist ist zeitlich nicht befristet. <strong>Sie k\u00f6nnen der Speicherung widersprechen, sofern Ihre Interessen unser berechtigtes Interesse \u00fcberwiegen.<\/strong><\/p>\n<h2>6. Plugins und Tools<\/h2>\n<h3>Wordfence<\/h3>\n<p>Wir haben Wordfence auf dieser Website eingebunden. Anbieter ist Defiant Inc., Defiant, Inc., 800 5th Ave Ste 4100, Seattle, WA 98104, USA (nachfolgend \u201eWordfence\u201c).<\/p>\n<p>Wordfence dient dem Schutz unserer Website vor unerw\u00fcnschten Zugriffen oder b\u00f6sartigen Cyberattacken. Zu diesem Zweck stellt unsere Website eine dauerhafte Verbindung zu den Servern von Wordfence her, damit Wordfence seine Datenbanken mit den auf unserer Website get\u00e4tigten Zugriffen abgleichen und ggf. blockieren kann.<\/p>\n<p>Die Verwendung von Wordfence erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an einem m\u00f6glichst effektiven Schutz seiner Website vor Cyberattacken. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger\u00e4t des Nutzers (z.&nbsp;B. Device-Fingerprinting) im Sinne des TDDDG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Die Daten\u00fcbertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest\u00fctzt. Details finden Sie hier: <a href=\"https:\/\/www.wordfence.com\/help\/general-data-protection-regulation\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.wordfence.com\/help\/general-data-protection-regulation\/<\/a>.<\/p>\n<p>Quelle: <a href=\"https:\/\/www.e-recht24.de\">https:\/\/www.e-recht24.de<\/a><\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf dieser Website [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-450","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Datenschutz - Meditrain center Patrick und Tim Kirstein GbR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/datenschutz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutz - Meditrain center Patrick und Tim Kirstein GbR\" \/>\n<meta property=\"og:description\" content=\"1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf dieser Website [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/datenschutz\/\" \/>\n<meta property=\"og:site_name\" content=\"Meditrain center Patrick und Tim Kirstein GbR\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-06T19:08:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"16\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/datenschutz\/\",\"url\":\"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/datenschutz\/\",\"name\":\"Datenschutz - Meditrain center Patrick und Tim Kirstein GbR\",\"isPartOf\":{\"@id\":\"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/#website\"},\"datePublished\":\"2025-08-08T11:42:11+00:00\",\"dateModified\":\"2026-06-06T19:08:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/datenschutz\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/datenschutz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/datenschutz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/#website\",\"url\":\"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/\",\"name\":\"Meditrain center Patrick und Tim Kirstein GbR\",\"description\":\"Rehasport in Idar Oberstein\",\"publisher\":{\"@id\":\"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/#organization\",\"name\":\"Meditrain center Patrick und Tim Kirstein GbR\",\"url\":\"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/rehasportportal.de\/wp-content\/uploads\/sites\/467\/2025\/07\/Rehasport_Portal_Logo_rgb.png\",\"contentUrl\":\"https:\/\/rehasportportal.de\/wp-content\/uploads\/sites\/467\/2025\/07\/Rehasport_Portal_Logo_rgb.png\",\"width\":945,\"height\":295,\"caption\":\"Meditrain center Patrick und Tim Kirstein GbR\"},\"image\":{\"@id\":\"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutz - Meditrain center Patrick und Tim Kirstein GbR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/datenschutz\/","og_locale":"de_DE","og_type":"article","og_title":"Datenschutz - Meditrain center Patrick und Tim Kirstein GbR","og_description":"1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf dieser Website [&hellip;]","og_url":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/datenschutz\/","og_site_name":"Meditrain center Patrick und Tim Kirstein GbR","article_modified_time":"2026-06-06T19:08:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"16\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/datenschutz\/","url":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/datenschutz\/","name":"Datenschutz - Meditrain center Patrick und Tim Kirstein GbR","isPartOf":{"@id":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/#website"},"datePublished":"2025-08-08T11:42:11+00:00","dateModified":"2026-06-06T19:08:48+00:00","breadcrumb":{"@id":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/datenschutz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/datenschutz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/datenschutz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/"},{"@type":"ListItem","position":2,"name":"Datenschutz"}]},{"@type":"WebSite","@id":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/#website","url":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/","name":"Meditrain center Patrick und Tim Kirstein GbR","description":"Rehasport in Idar Oberstein","publisher":{"@id":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/#organization","name":"Meditrain center Patrick und Tim Kirstein GbR","url":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/#\/schema\/logo\/image\/","url":"https:\/\/rehasportportal.de\/wp-content\/uploads\/sites\/467\/2025\/07\/Rehasport_Portal_Logo_rgb.png","contentUrl":"https:\/\/rehasportportal.de\/wp-content\/uploads\/sites\/467\/2025\/07\/Rehasport_Portal_Logo_rgb.png","width":945,"height":295,"caption":"Meditrain center Patrick und Tim Kirstein GbR"},"image":{"@id":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/wp-json\/wp\/v2\/pages\/450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/wp-json\/wp\/v2\/comments?post=450"}],"version-history":[{"count":8,"href":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/wp-json\/wp\/v2\/pages\/450\/revisions"}],"predecessor-version":[{"id":1099,"href":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/wp-json\/wp\/v2\/pages\/450\/revisions\/1099"}],"wp:attachment":[{"href":"https:\/\/rehasportportal.de\/meditrain-center-patrick-und-tim-kirstein-gbr\/wp-json\/wp\/v2\/media?parent=450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}